{"id":16622,"date":"2023-05-25T17:03:19","date_gmt":"2023-05-25T16:03:19","guid":{"rendered":"https:\/\/www.lucca.fr\/magazine\/?p=16622"},"modified":"2025-07-10T14:17:35","modified_gmt":"2025-07-10T13:17:35","slug":"enjeux-facturation-electronique","status":"publish","type":"post","link":"https:\/\/www.lucca.fr\/magazine\/administration\/comptabilite\/enjeux-facturation-electronique","title":{"rendered":"Facturation \u00e9lectronique: comprendre les enjeux et vous y pr\u00e9parer"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16622\" class=\"elementor elementor-16622\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1885564 e-flex e-con-boxed e-con e-parent\" data-id=\"1885564\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-89c8d63 e-con-full e-flex e-con e-child\" data-id=\"89c8d63\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-07d8a20 elementor-widget elementor-widget-text-editor\" data-id=\"07d8a20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La fraude \u00e0 la TVA repr\u00e9sente, selon l\u2019Insee, un manque \u00e0 gagner d\u2019environ 20 milliards d\u2019euros pour l\u2019\u00c9tat fran\u00e7ais. L\u2019administration a donc souhait\u00e9 \u00eatre inform\u00e9e de l\u2019ensemble des transactions commerciales ayant lieu entre entreprises, en vue de faciliter le contr\u00f4le des montants de TVA d\u00e9clar\u00e9s.<\/p><p>\u00a0<\/p><p>Par cons\u00e9quent, l\u2019\u00e9mission des factures clients et la r\u00e9ception des factures fournisseurs au format \u00e9lectronique ainsi que leur d\u00e9claration aupr\u00e8s de l\u2019administration fiscale sera mise en place.<\/p><p>\u00a0<\/p><p>Cet article d\u00e9crit ce \u00e0 quoi vous devez vous attendre et comment proc\u00e9der pour vous conformer \u00e0 cette nouvelle l\u00e9gislation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0a77e8 elementor-widget elementor-widget-table-of-contents\" data-id=\"f0a77e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;headings_by_tags&quot;:[&quot;h2&quot;],&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;marker_view&quot;:&quot;numbers&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<div class=\"elementor-toc__header-title\">\n\t\t\t\tSommaire\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__f0a77e8\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<svg class=\"elementor-toc__spinner eicon-animation-spin e-font-icon-svg e-eicon-loading\" aria-hidden=\"true\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M500 975V858C696 858 858 696 858 500S696 142 500 142 142 304 142 500H25C25 237 238 25 500 25S975 237 975 500 763 975 500 975Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e179575 elementor-widget elementor-widget-heading\" data-id=\"e179575\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi cette r\u00e9forme voit le jour ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9140c5b elementor-widget elementor-widget-heading\" data-id=\"9140c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Les deux obligations de la r\u00e9forme de la facturation \u00e9lectronique<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0369bf2 elementor-widget elementor-widget-text-editor\" data-id=\"0369bf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La r\u00e9forme comporte deux volets, applicables en fonction du type d\u2019op\u00e9ration :<\/p><ul><li><strong>le e-invoicing,<\/strong>\u00a0il consiste \u00e0 \u00e9mettre et recevoir des factures sous format \u00e9lectronique et \u00e0 transmettre des donn\u00e9es, comme les statuts de facture, \u00e0 l\u2019administration fiscale. Cette transmission de factures se fait obligatoirement via une plateforme. Elle concerne <strong>les op\u00e9rations entre entreprises fran\u00e7aises assujetties \u00e0 la TVA ;<\/strong><\/li><li><strong>le e-reporting,\u00a0<\/strong>il ne concerne que des cas sp\u00e9cifiques tels que le traitement des factures \u00e9mises ou re\u00e7ues par une entreprise non fran\u00e7aise (c\u2019est-\u00e0-dire, le commerce avec les entreprises \u00e9trang\u00e8res) ou l\u2019envoi de facture \u00e0 des <strong>particuliers<\/strong>.<\/li><\/ul><p>Dans ce cas, vous n\u2019\u00eates pas oblig\u00e9 d\u2019\u00e9mettre ou recevoir des factures au format \u00e9lectronique. En revanche, vous devez transmettre p\u00e9riodiquement les informations li\u00e9es \u00e0 la facture \u00e0 l\u2019administration fiscale (par exemple, les donn\u00e9es de transaction ou la date \u00e0 laquelle le paiement a \u00e9t\u00e9 effectu\u00e9).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac53fc7 elementor-widget elementor-widget-image\" data-id=\"ac53fc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"297\" src=\"https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/3G9mrRu29a-1024x358.png\" class=\"attachment-large size-large wp-image-16625\" alt=\"\" srcset=\"https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/3G9mrRu29a-1024x358.png 1024w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/3G9mrRu29a-300x105.png 300w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/3G9mrRu29a-768x268.png 768w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/3G9mrRu29a-360x126.png 360w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/3G9mrRu29a.png 1219w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9d7ab1 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"a9d7ab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">\u00c0 noter :<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">au sens de la loi, une facture \u00e9lectronique est une facture directement cr\u00e9\u00e9e sous forme \u00e9lectronique dans un des formats reconnus : FacturX, UBL ou CII. Autrement dit, en cas de contr\u00f4le, les factures sous format PDF ne pourront plus \u00eatre utilis\u00e9es pour justifier les transactions domestiques entre assujettis \u00e0 la TVA.\nParmi ces formats, FacturX est celui qui est susceptible d\u2019\u00eatre le plus largement adopt\u00e9. Il permet d'avoir une facture lisible sous format PDF, ainsi qu'un fichier XML contenant les donn\u00e9es de la facture, compr\u00e9hensibles par un outil informatique.<\/span>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1db7818a cta-img e-flex e-con-boxed e-con e-parent\" data-id=\"1db7818a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-61a24fdf e-flex e-con-boxed e-con e-child\" data-id=\"61a24fdf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38de0bd9 elementor-widget elementor-widget-heading\" data-id=\"38de0bd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Kit pratique : pr\u00e9parez votre entreprise \u00e0 la facturation \u00e9lectronique<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf9d95f elementor-widget elementor-widget-text-editor\" data-id=\"5bf9d95f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"151\" data-end=\"301\">Retrouvez toutes les ressources cl\u00e9s pour comprendre la r\u00e9forme, anticiper vos obligations et piloter sereinement votre projet de d\u00e9mat\u00e9rialisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f208e9a elementor-widget elementor-widget-button\" data-id=\"2f208e9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/info.lucca.fr\/l\/950782\/2025-06-26\/5zj48g\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger le kit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f177f61 e-flex e-con-boxed e-con e-parent\" data-id=\"f177f61\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63b43c4 elementor-widget elementor-widget-heading\" data-id=\"63b43c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Les \u00e9ch\u00e9ances de la r\u00e9forme<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4248d2c elementor-widget elementor-widget-text-editor\" data-id=\"4248d2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les obligations d\u2019\u00e9mission et de r\u00e9ception des factures \u00e9lectroniques suivent deux calendriers distincts.<\/p><p>\u00a0<\/p><p>Tout d\u2019abord, les entreprises devront toutes \u00eatre capables de recevoir des factures \u00e9lectroniques.<\/p><p>\u00a0<\/p><p>Le d\u00e9ploiement de la r\u00e9forme pour l\u2019\u00e9mission de factures \u00e9lectroniques vers des tiers se fera, quant \u00e0 lui, de mani\u00e8re progressive, en fonction de la taille de l\u2019entreprise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1a7bd2 elementor-widget elementor-widget-text-editor\" data-id=\"f1a7bd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019obligation de e-reporting suit le m\u00eame calendrier que celui d\u2019e-invoicing.<\/p><p>\u00a0<\/p><p>La taille des entreprises est appr\u00e9ci\u00e9e selon l\u2019effectif et le chiffre d\u2019affaires ou le total de bilan.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87d6983 elementor-widget elementor-widget-image\" data-id=\"87d6983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"850\" height=\"273\" src=\"https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/0ZA2Q0ZLew-1024x329.png\" class=\"attachment-large size-large wp-image-16627\" alt=\"\" srcset=\"https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/0ZA2Q0ZLew-1024x329.png 1024w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/0ZA2Q0ZLew-300x96.png 300w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/0ZA2Q0ZLew-768x247.png 768w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/0ZA2Q0ZLew-360x116.png 360w, https:\/\/www.lucca.fr\/magazine\/wp-content\/uploads\/2023\/05\/0ZA2Q0ZLew.png 1196w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e5b2f2 elementor-widget elementor-widget-heading\" data-id=\"4e5b2f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment seront transmises les factures avec la r\u00e9forme ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-530dee0 elementor-widget elementor-widget-heading\" data-id=\"530dee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Une plateforme interm\u00e9diaire obligatoire pour transmettre les factures<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2463145 elementor-widget elementor-widget-text-editor\" data-id=\"2463145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La r\u00e9forme implique une transmission obligatoire des factures \u00e9lectroniques par le biais de plateformes interm\u00e9diaires, publiques ou priv\u00e9es. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9b95b7 elementor-widget elementor-widget-heading\" data-id=\"f9b95b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Le Portail Public de Facturation <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c3851d elementor-widget elementor-widget-text-editor\" data-id=\"4c3851d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le Portail Public de Facturation (PPF) est le <strong>tiers de confiance public<\/strong> qui permet la transmission des factures entre un fournisseur et son client. Il met \u00e0 disposition un annuaire unique pour router les factures vers leurs destinataires et centralise les donn\u00e9es de facturation pour les transmettre \u00e0 l\u2019administration fiscale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-667e9f3 elementor-widget elementor-widget-heading\" data-id=\"667e9f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Les Plateformes de D\u00e9mat\u00e9rialisation Partenaires<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab6146 elementor-widget elementor-widget-text-editor\" data-id=\"2ab6146\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour faciliter l\u2019adoption de la r\u00e9forme, des <strong>plateformes priv\u00e9es immatricul\u00e9es par l\u2019Etat<\/strong> auront \u00e9galement comme mission la transmission des factures et pourront \u00eatre utilis\u00e9es par les entreprises \u00e0 la place du PPF. Elles transmettront les donn\u00e9es issues des factures \u00e0 l\u2019administration fiscale via le PPF.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9443fc0 elementor-widget elementor-widget-heading\" data-id=\"9443fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quelles cons\u00e9quences pour votre entreprise ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af92c74 elementor-widget elementor-widget-heading\" data-id=\"af92c74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9ception des factures<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19b725f elementor-widget elementor-widget-text-editor\" data-id=\"19b725f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour anticiper votre mise en conformit\u00e9, votre priorit\u00e9 est de choisir une plateforme publique (le PPF) ou priv\u00e9e (une PDP) qui sera en mesure de recevoir les factures \u00e9lectroniques.<\/p><p>\u00a0<\/p><p>Si vous utilisez actuellement un logiciel qui permet de traiter vos factures fournisseurs, il y a de grandes chances pour que vous n\u2019ayez rien \u00e0 faire : celui-ci se mettra en conformit\u00e9 avec cette nouvelle r\u00e9glementation. Vous pouvez vous rapprocher de l\u2019\u00e9diteur pour savoir ce qu\u2019il en est.<\/p><p>\u00a0<\/p><p>Si vous suivez actuellement vos factures fournisseurs manuellement (par exemple, via un fichier Excel ou un d\u00e9p\u00f4t dans un drive), vous pouvez profiter de cette occasion pour vous \u00e9quiper d\u2019un logiciel de gestion des factures fournisseurs. Sinon, le PPF vous donnera la possibilit\u00e9 de r\u00e9cup\u00e9rer manuellement les factures \u00e9lectroniques d\u00e9pos\u00e9es par les fournisseurs.<\/p><p>\u00a0<\/p><p>Dans tous les cas, vous devrez vous assurer que les factures que vous avez re\u00e7ues sont bien archiv\u00e9es \u00e9lectroniquement (soit par votre prestataire, soit par vous-m\u00eame) et que certaines informations li\u00e9es \u00e0 leur cycle de vie sont transmises \u00e0 l\u2019\u00c9tat (par exemple, que la facture a bien \u00e9t\u00e9 re\u00e7ue et est en cours de traitement).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-847a623 elementor-widget elementor-widget-heading\" data-id=\"847a623\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9mission des factures<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88c32dc elementor-widget elementor-widget-text-editor\" data-id=\"88c32dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lorsque vous serez dans l\u2019obligation d\u2019\u00e9mettre des factures au format \u00e9lectronique, vous devrez respecter plusieurs crit\u00e8res :<\/p><ul><li>que la facture \u00e9mise soit \u00e0 des formats propos\u00e9s dans le cadre de la r\u00e9forme (UBL, CII ou FacturX) ;<\/li><li>qu\u2019elle comporte une liste de <a href=\"https:\/\/www.impots.gouv.fr\/sites\/default\/files\/media\/1_metier\/2_professionnel\/EV\/2_gestion\/290_facturation_electronique\/tableau-des-donnees-de-facture-a-transmettre-sous-format-structure---10-10-2022.pdf\" target=\"_blank\" rel=\"noopener\">donn\u00e9es obligatoires<\/a> ;<\/li><li>qu\u2019elle soit archiv\u00e9e \u00e9lectroniquement ;<\/li><li>que <strong>l\u2019\u00e9volution du cycle de vie<\/strong> de ces factures soit suvi via des statuts (d\u00e9pos\u00e9e, encaiss\u00e9e, litige, etc.). Certains d\u2019entre eux devront \u00eatre partag\u00e9s \u00e0 l\u2019administration.<\/li><\/ul><div>\u00a0<\/div><p>Comme pour la partie r\u00e9ception des factures, si vous utilisez actuellement un logiciel vous permettant de g\u00e9n\u00e9rer vos factures clients, il y a fort \u00e0 parier que celui-ci se mette en conformit\u00e9 avec les obligations li\u00e9es \u00e0 la r\u00e9forme.<\/p><p>\u00a0<\/p><p>Si vous n\u2019utilisez pas de logiciel \u00e0 l\u2019heure actuelle, il sera possible de d\u00e9poser manuellement les factures sur le site du PPF (via un formulaire \u00e0 remplir) ainsi que de mettre \u00e0 jour le statut d\u2019une facture pr\u00e9alablement d\u00e9pos\u00e9e.<\/p><p>\u00a0<\/p><p>Au lancement de la r\u00e9forme, vous pourrez toujours d\u00e9poser un pdf sur le site du PPF. Il sera lu automatiquement et vous n\u2019aurez plus qu\u2019\u00e0 compl\u00e9ter les donn\u00e9es manquantes avant de valider l\u2019envoi de la facture au client.<\/p><p>\u00a0<\/p><p>Il existe des moyens d\u2019automatiser ces diff\u00e9rents traitements. C\u2019est le r\u00f4le des <strong>op\u00e9rateurs de d\u00e9mat\u00e9rialisation.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3eb49a elementor-widget elementor-widget-heading\" data-id=\"a3eb49a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les op\u00e9rateurs de d\u00e9mat\u00e9rialisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d985432 elementor-widget elementor-widget-text-editor\" data-id=\"d985432\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Votre entreprise sera donc confront\u00e9e \u00e0 de nouvelles contraintes, que ce soit lors de l\u2019\u00e9mission ou de la r\u00e9ception des factures : gestion de nouveaux formats, liste de donn\u00e9es obligatoires, mises \u00e0 jour de statuts, etc.<\/p><p><br><\/p>\n<p><\/p>\n<p>Bien que cela puisse sembler complexe \u00e0 mettre en place, il est en r\u00e9alit\u00e9 possible de g\u00e9rer l\u2019ensemble de ces obligations de mani\u00e8re informatis\u00e9e gr\u00e2ce aux <strong>op\u00e9rateurs de d\u00e9mat\u00e9rialisation<\/strong>.<\/p><p><br><\/p>\n<p><\/p>\n<p>Ces logiciels existent d\u00e9j\u00e0 : ce sont ceux qui vous permettent d\u2019\u00e9mettre des factures clients ou de traiter des factures fournisseurs. Ce sera \u00e0 eux de prendre en compte les contraintes de la r\u00e9forme dans leur planning d\u2019\u00e9volutions.<\/p><p><br><\/p>\n<p><\/p>\n<p>Par ailleurs, ces prestataires doivent \u00eatre en mesure de g\u00e9rer des factures non \u00e9lectroniques (par exemple, celles provenant de fournisseurs \u00e9trangers) et de centraliser toutes vos factures en un seul endroit en vue de leur traitement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3daa967f cta-img e-flex e-con-boxed e-con e-parent\" data-id=\"3daa967f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5c864de6 e-flex e-con-boxed e-con e-child\" data-id=\"5c864de6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2459bbf1 elementor-widget elementor-widget-heading\" data-id=\"2459bbf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Avec Lucca Factures, simplifiez le traitement de vos factures fournisseurs :<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50d2c2a8 elementor-widget elementor-widget-text-editor\" data-id=\"50d2c2a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>d\u00e9mat\u00e9rialisez et centralisez toutes vos factures ;<\/li><li>payez en un clic par virement ou g\u00e9n\u00e9rez facilement vos fichiers SEPA ;<\/li><li>automatisez l\u2019export comptable pour gagner en efficacit\u00e9.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21cede82 elementor-widget elementor-widget-button\" data-id=\"21cede82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/info.lucca.fr\/l\/950782\/2025-06-26\/5zj44g\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tester la solution<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La fraude \u00e0 la TVA repr\u00e9sente, selon l\u2019Insee, un manque \u00e0 gagner d\u2019environ 20 milliards d\u2019euros pour l\u2019\u00c9tat fran\u00e7ais. L\u2019administration a donc souhait\u00e9 \u00eatre inform\u00e9e de l\u2019ensemble des transactions commerciales ayant lieu entre entreprises, en&#8230;<\/p>\n","protected":false},"author":41,"featured_media":29875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[150],"tags":[],"post_folder":[],"class_list":["post-16622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comptabilite"],"_links":{"self":[{"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/posts\/16622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/comments?post=16622"}],"version-history":[{"count":4,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/posts\/16622\/revisions"}],"predecessor-version":[{"id":33814,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/posts\/16622\/revisions\/33814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/media\/29875"}],"wp:attachment":[{"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/media?parent=16622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/categories?post=16622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/tags?post=16622"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.lucca.fr\/magazine\/wp-json\/wp\/v2\/post_folder?post=16622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}